{"id":46967,"date":"2026-05-12T23:28:48","date_gmt":"2026-05-12T21:28:48","guid":{"rendered":"https:\/\/multiplica.com\/?post_type=events_post&#038;p=46967"},"modified":"2026-05-12T23:31:54","modified_gmt":"2026-05-12T21:31:54","slug":"capability-program-research-mindset-for-product-business-teams","status":"publish","type":"events_post","link":"https:\/\/multiplica.com\/en\/eventos-nuevos\/capability-program-research-mindset-for-product-business-teams\/","title":{"rendered":"Research Mindset for Product &amp; Business Teams"},"content":{"rendered":"<div class=\"c-display-paragraph font-moderat-l-regular\"><div class=\"o-container\"><div class=\"o-row\"><div class=\"o-col-md-16 o-offset-md-1\"><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":67,"featured_media":46971,"template":"","tags":[155,154,131,156,157,153,129,138],"event_type":[],"class_list":["post-46967","events_post","type-events_post","status-publish","has-post-thumbnail","hentry","tag-academy","tag-capability-program","tag-growth","tag-knowledge","tag-multiplica","tag-research","tag-talento","tag-tendencias-digitales"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Capability Program Research Mindset for Product &amp; Business Teams. | Multiplica Academy<\/title>\n<meta name=\"description\" content=\"C\u00f3mo desarrollar equipos que entienden mejor a las personas para tomar decisiones m\u00e1s inteligentes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/multiplica.com\/en\/eventos-nuevos\/capability-program-research-mindset-for-product-business-teams\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Research Mindset for Product &amp; Business Teams. | Multiplica Academy\" \/>\n<meta property=\"og:description\" content=\"C\u00f3mo desarrollar equipos que entienden mejor a las personas para tomar decisiones m\u00e1s inteligentes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/multiplica.com\/en\/eventos-nuevos\/capability-program-research-mindset-for-product-business-teams\/\" \/>\n<meta property=\"og:site_name\" content=\"Multiplica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/multiplicanet\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T21:31:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/multiplica.com\/wp-content\/uploads\/2026\/05\/03-imagen-landing-capability-program-01-research-mindset-for-product-business-teams-600x507.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"507\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@multiplica\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/multiplica.com\/en\/eventos-nuevos\/capability-program-research-mindset-for-product-business-teams\/\",\"url\":\"https:\/\/multiplica.com\/en\/eventos-nuevos\/capability-program-research-mindset-for-product-business-teams\/\",\"name\":\"Capability Program Research Mindset for Product & Business Teams. | Multiplica Academy\",\"isPartOf\":{\"@id\":\"https:\/\/multiplica.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/multiplica.com\/en\/eventos-nuevos\/capability-program-research-mindset-for-product-business-teams\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/multiplica.com\/en\/eventos-nuevos\/capability-program-research-mindset-for-product-business-teams\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/multiplica.com\/wp-content\/uploads\/2026\/05\/03-imagen-landing-capability-program-01-research-mindset-for-product-business-teams-600x507.png\",\"datePublished\":\"2026-05-12T21:28:48+00:00\",\"dateModified\":\"2026-05-12T21:31:54+00:00\",\"description\":\"C\u00f3mo desarrollar equipos que entienden mejor a las personas para tomar decisiones m\u00e1s inteligentes.\",\"breadcrumb\":{\"@id\":\"https:\/\/multiplica.com\/en\/eventos-nuevos\/capability-program-research-mindset-for-product-business-teams\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/multiplica.com\/en\/eventos-nuevos\/capability-program-research-mindset-for-product-business-teams\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/multiplica.com\/en\/eventos-nuevos\/capability-program-research-mindset-for-product-business-teams\/#primaryimage\",\"url\":\"https:\/\/multiplica.com\/wp-content\/uploads\/2026\/05\/03-imagen-landing-capability-program-01-research-mindset-for-product-business-teams-600x507.png\",\"contentUrl\":\"https:\/\/multiplica.com\/wp-content\/uploads\/2026\/05\/03-imagen-landing-capability-program-01-research-mindset-for-product-business-teams-600x507.png\",\"width\":600,\"height\":507,\"caption\":\"Imagen_Landing Capability Program 01 Research Mindset for Product & Business Teams\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/multiplica.com\/en\/eventos-nuevos\/capability-program-research-mindset-for-product-business-teams\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/multiplica.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventos Nuevos\",\"item\":\"https:\/\/multiplica.com\/en\/eventos-nuevos\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Research Mindset for Product &amp; Business Teams\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/multiplica.com\/en\/#website\",\"url\":\"https:\/\/multiplica.com\/en\/\",\"name\":\"Multiplica\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/multiplica.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/multiplica.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/multiplica.com\/en\/#organization\",\"name\":\"Multiplica\",\"alternateName\":\"Multiplica\",\"url\":\"https:\/\/multiplica.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/multiplica.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/multiplica.com\/wp-content\/uploads\/2025\/07\/logo-multiplica-696.png\",\"contentUrl\":\"https:\/\/multiplica.com\/wp-content\/uploads\/2025\/07\/logo-multiplica-696.png\",\"width\":696,\"height\":696,\"caption\":\"Multiplica\"},\"image\":{\"@id\":\"https:\/\/multiplica.com\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/multiplicanet\/\",\"https:\/\/x.com\/multiplica\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Capability Program Research Mindset for Product & Business Teams. | Multiplica Academy","description":"C\u00f3mo desarrollar equipos que entienden mejor a las personas para tomar decisiones m\u00e1s inteligentes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/multiplica.com\/en\/eventos-nuevos\/capability-program-research-mindset-for-product-business-teams\/","og_locale":"es_ES","og_type":"article","og_title":"Research Mindset for Product & Business Teams. | Multiplica Academy","og_description":"C\u00f3mo desarrollar equipos que entienden mejor a las personas para tomar decisiones m\u00e1s inteligentes.","og_url":"https:\/\/multiplica.com\/en\/eventos-nuevos\/capability-program-research-mindset-for-product-business-teams\/","og_site_name":"Multiplica","article_publisher":"https:\/\/www.facebook.com\/multiplicanet\/","article_modified_time":"2026-05-12T21:31:54+00:00","og_image":[{"width":600,"height":507,"url":"https:\/\/multiplica.com\/wp-content\/uploads\/2026\/05\/03-imagen-landing-capability-program-01-research-mindset-for-product-business-teams-600x507.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@multiplica","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/multiplica.com\/en\/eventos-nuevos\/capability-program-research-mindset-for-product-business-teams\/","url":"https:\/\/multiplica.com\/en\/eventos-nuevos\/capability-program-research-mindset-for-product-business-teams\/","name":"Capability Program Research Mindset for Product & Business Teams. | Multiplica Academy","isPartOf":{"@id":"https:\/\/multiplica.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/multiplica.com\/en\/eventos-nuevos\/capability-program-research-mindset-for-product-business-teams\/#primaryimage"},"image":{"@id":"https:\/\/multiplica.com\/en\/eventos-nuevos\/capability-program-research-mindset-for-product-business-teams\/#primaryimage"},"thumbnailUrl":"https:\/\/multiplica.com\/wp-content\/uploads\/2026\/05\/03-imagen-landing-capability-program-01-research-mindset-for-product-business-teams-600x507.png","datePublished":"2026-05-12T21:28:48+00:00","dateModified":"2026-05-12T21:31:54+00:00","description":"C\u00f3mo desarrollar equipos que entienden mejor a las personas para tomar decisiones m\u00e1s inteligentes.","breadcrumb":{"@id":"https:\/\/multiplica.com\/en\/eventos-nuevos\/capability-program-research-mindset-for-product-business-teams\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/multiplica.com\/en\/eventos-nuevos\/capability-program-research-mindset-for-product-business-teams\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/multiplica.com\/en\/eventos-nuevos\/capability-program-research-mindset-for-product-business-teams\/#primaryimage","url":"https:\/\/multiplica.com\/wp-content\/uploads\/2026\/05\/03-imagen-landing-capability-program-01-research-mindset-for-product-business-teams-600x507.png","contentUrl":"https:\/\/multiplica.com\/wp-content\/uploads\/2026\/05\/03-imagen-landing-capability-program-01-research-mindset-for-product-business-teams-600x507.png","width":600,"height":507,"caption":"Imagen_Landing Capability Program 01 Research Mindset for Product & Business Teams"},{"@type":"BreadcrumbList","@id":"https:\/\/multiplica.com\/en\/eventos-nuevos\/capability-program-research-mindset-for-product-business-teams\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/multiplica.com\/en\/"},{"@type":"ListItem","position":2,"name":"Eventos Nuevos","item":"https:\/\/multiplica.com\/en\/eventos-nuevos\/"},{"@type":"ListItem","position":3,"name":"Research Mindset for Product &amp; Business Teams"}]},{"@type":"WebSite","@id":"https:\/\/multiplica.com\/en\/#website","url":"https:\/\/multiplica.com\/en\/","name":"Multiplica","description":"","publisher":{"@id":"https:\/\/multiplica.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/multiplica.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/multiplica.com\/en\/#organization","name":"Multiplica","alternateName":"Multiplica","url":"https:\/\/multiplica.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/multiplica.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/multiplica.com\/wp-content\/uploads\/2025\/07\/logo-multiplica-696.png","contentUrl":"https:\/\/multiplica.com\/wp-content\/uploads\/2025\/07\/logo-multiplica-696.png","width":696,"height":696,"caption":"Multiplica"},"image":{"@id":"https:\/\/multiplica.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/multiplicanet\/","https:\/\/x.com\/multiplica"]}]}},"_links":{"self":[{"href":"https:\/\/multiplica.com\/en\/wp-json\/wp\/v2\/events_post\/46967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/multiplica.com\/en\/wp-json\/wp\/v2\/events_post"}],"about":[{"href":"https:\/\/multiplica.com\/en\/wp-json\/wp\/v2\/types\/events_post"}],"author":[{"embeddable":true,"href":"https:\/\/multiplica.com\/en\/wp-json\/wp\/v2\/users\/67"}],"version-history":[{"count":3,"href":"https:\/\/multiplica.com\/en\/wp-json\/wp\/v2\/events_post\/46967\/revisions"}],"predecessor-version":[{"id":46976,"href":"https:\/\/multiplica.com\/en\/wp-json\/wp\/v2\/events_post\/46967\/revisions\/46976"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/multiplica.com\/en\/wp-json\/wp\/v2\/media\/46971"}],"wp:attachment":[{"href":"https:\/\/multiplica.com\/en\/wp-json\/wp\/v2\/media?parent=46967"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/multiplica.com\/en\/wp-json\/wp\/v2\/tags?post=46967"},{"taxonomy":"event_type","embeddable":true,"href":"https:\/\/multiplica.com\/en\/wp-json\/wp\/v2\/event_type?post=46967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}